{"id":60,"count":1,"description":"","link":"https:\/\/trementinalux.com\/Blog\/tag\/cuerpos-politizados\/","name":"cuerpos politizados","slug":"cuerpos-politizados","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts?tags=60"},{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/pmb_content?tags=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}