{"id":4955,"date":"2017-01-23T14:04:53","date_gmt":"2017-01-23T14:04:53","guid":{"rendered":"http:\/\/trementinalux.com\/Blog\/?p=4955"},"modified":"2017-01-23T14:19:47","modified_gmt":"2017-01-23T14:19:47","slug":"dias-de-jallikattu-y-rosas-os-juro-que-no-sabeis-lo-que-es-vivir-en-india","status":"publish","type":"post","link":"https:\/\/trementinalux.com\/Blog\/dias-de-jallikattu-y-rosas-os-juro-que-no-sabeis-lo-que-es-vivir-en-india\/","title":{"rendered":"Dias de Jallikattu y rosas. Os juro que no sab\u00e9is lo que es vivir en India&#8230;"},"content":{"rendered":"<p>Vale, me pilla en caliente. Salgo de casa esta ma\u00f1ana, voy a la library, paso horas estudiando acerca de <a href=\"http:\/\/glefas.org\/los-feminismos-decoloniales-miradas-criticas-sobre-la-subordinacion-de-las-mujeres\/\">feminismos decoloniales<\/a>, y cuando voy a regresar, todas las grandes v\u00edas de Chennai est\u00e1n cortadas por las protestas para dar soporte al Jallikattu.<\/p>\n<p><strong>Os recuerdo:<\/strong><\/p>\n<p>Diciembre, <a href=\"http:\/\/trementinalux.com\/Blog\/el-genero-como-categoria-de-analisis-veinticuatro-millones-de-billetes-menos-y-treinta-anos-despues-de-joan-wallach-scott\/\">demonetizan<\/a>, es decir, desaparece todo el papel moneda\u00a0de 500 y 1000 rupias. Quince d\u00edas despu\u00e9s muere de un infarto la <a href=\"http:\/\/trementinalux.com\/Blog\/women-with-pyrotechnic-heart\/\">Chief Minister<\/a>, estado de excepci\u00f3n y duelo, unos\u00a0d\u00edas despu\u00e9s el cicl\u00f3n <a href=\"http:\/\/www.thehindu.com\/news\/national\/tamil-nadu\/Cyclone-Vardah-In-pictures\/article16797291.ece1\">Vardah <\/a>arrasa quince mil \u00e1rboles en la ciudad y deja catorce mil toneladas de le\u00f1a en las calles inundadas. Sin luz, sin dinero, sin tel\u00e9fono, sin wifi, con agua, arroz y dhal en la despensa, eso s\u00ed. En Espa\u00f1a la gente andar\u00eda cabreada todo el d\u00eda y buscando culpables, aqu\u00ed sin embargo he aprendido a decir moviendo la cabecita a los lados: <a href=\"https:\/\/www.youtube.com\/watch?v=234u2ZV8HNY\">What can I do<\/a>? Y ahora llevamos una semana de vidilla gracias al Jallikattu.<\/p>\n<p>El <a href=\"https:\/\/www.youtube.com\/watch?v=haLimnzibxY\">Jallikattu<\/a> es un \u00abdeporte\u00bb ancestral que consiste en coger a los toros de la chepa y aguantar ah\u00ed un rato. El gobierno lo prohibi\u00f3 por maltrato animal y las gentes de Tamil Nadu quieren recuperarlo porque es una tradici\u00f3n y les encanta. No matan al toro, pero le hacen pasar un rato apurado. \u00bfOs suena? Lo imagino.<\/p>\n<p>Hoy grupos de entre veinte y treinta mujeres con ni\u00f1os y alg\u00fan que otro hombre, han conseguido sentarse pac\u00edficamente y cortar todas las grandes v\u00edas de una ciudad de no-se-cuantos millones de habitantes. As\u00ed. Esto me ha permitido, al finalizar el d\u00eda, regresar a casa andando, (por primera vez en un a\u00f1o) recorriendo todos los lugares de bloqueo de las grandes avenidas, saludando y felicitando a las gentes de aqu\u00ed su haza\u00f1a: cortar el desmedidamente asqueroso tr\u00e1fico, y os aseguro que una no sabe lo que es la palabra tr\u00e1fico hasta que no la utiliza aqu\u00ed. La calle tomada en India un 23 de enero.<\/p>\n<p>Un joven manifestante nos explicaba que esto es el principio de la revoluci\u00f3n. Y en efecto, aunque estamos en invierno, parece una primavera India. Porque no es un problema de toros s\u00ed o toros no, sino de identidad nacional, de identidad de castas, de identidad entre norte y sur, en la \u00e9poca de la megaglobalizaci\u00f3n. As\u00ed estamos, despertando a la serpiente&#8230; I&#8217;m just gonna let it fly&#8230;<\/p>\n<p>Al final, tras una semana de protestas pac\u00edficas en la playa de Marina Beach (en las que la gente ha participado con el mismo entusiasmo que ponemos nosotr@s yendo al FIB de Benicassim o\u00a0al Low de Benidorm)\u00a0el gobierno central ha decidido aprobar de nuevo el Jallikattu y el tr\u00e1fico acaba de volver a la ciudad&#8230; Snif.<\/p>\n<p>Aqu\u00ed una foto de Pullitzer del momentazo en mi barrio, uno de ellos. Os juro que los ni\u00f1@s no paran quietos celebr\u00e1ndolo. \u00bfQu\u00e9 si soy animalista o no? Buff, no esper\u00e9is de m\u00ed, viviendo aqu\u00ed, una actitud colonialista de salvadora de nadie, ni juicios de valor ni redenciones, ni explicaciones occidentales de lo que aqu\u00ed pasa. Una cosa es turistear, otra vivir aqu\u00ed siendo mujer y teniendo el pelo y la piel tan blanca, y otra entender la complejidad de sus circunstancias culturales sin ponerse por encima. Pues eso, trabajando en una actitud feminista decolonial con mis vecin@s, que tiene tela.<\/p>\n<p>Yeahhh living in India la vida loca, amazing time, believe me!<\/p>\n<p>Thanks Universe.<\/p>\n<p>TREMENTINA LUX<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vale, me pilla en caliente. Salgo de casa esta ma\u00f1ana, voy a la library, paso horas estudiando acerca de feminismos decoloniales, y cuando voy a regresar, todas las grandes v\u00edas de Chennai est\u00e1n cortadas por las protestas para dar soporte al Jallikattu. Os recuerdo: Diciembre, demonetizan, es decir, desaparece todo el papel moneda\u00a0de 500 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,87],"tags":[326,325,288,324],"class_list":["post-4955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","category-vindicaciones-nomadas","tag-chennai","tag-feminismos-decoloniales","tag-india","tag-jallikattu"],"jetpack_featured_media_url":"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2017\/01\/JALLIKATTU-TREMENTINALUX.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/comments?post=4955"}],"version-history":[{"count":12,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4955\/revisions"}],"predecessor-version":[{"id":4969,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4955\/revisions\/4969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media\/4958"}],"wp:attachment":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media?parent=4955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/categories?post=4955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags?post=4955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}