{"id":4734,"date":"2018-05-03T11:31:27","date_gmt":"2018-05-03T11:31:27","guid":{"rendered":"http:\/\/trementinalux.com\/Blog\/?p=4734"},"modified":"2018-05-04T12:11:10","modified_gmt":"2018-05-04T12:11:10","slug":"the-magic-alphabetical-stairs-happy-art-healthy-project-hah","status":"publish","type":"post","link":"https:\/\/trementinalux.com\/Blog\/the-magic-alphabetical-stairs-happy-art-healthy-project-hah\/","title":{"rendered":"THE MAGIC ALPHABETICAL STAIRS. Happy Art Healthy Project. (HAH)"},"content":{"rendered":"<h3><strong>Let me tell you a lovely story, once upon a time, recently&#8230;<\/strong><\/h3>\n<p><strong>Parte 1. Tienes que conocer a Virginie.<\/strong><\/p>\n<p>A ella le hab\u00edan hablado de m\u00ed. Y a m\u00ed, de ella. Un d\u00eda, en el\u00a0<em>Lunch<\/em> mexicano que organiz\u00f3 una maravillosa amiga en com\u00fan, gracias Vero, nos conocimos. A los dos minutos\u00a0Virginie me propuso pintar una escalera en <em>Injanbakkam School,<\/em> un colegio indio al que la ONG <em>Namma Beach Namma Chennai<\/em> ayuda desinteresadamente. Acepte encantada.<\/p>\n<p>A los dos d\u00edas est\u00e1bamos en su casa viendo fotos de escaleras. \u2013Los estudiantes est\u00e1n aprendiendo ingles, pero no tienen muchos recursos. Es una escuela en Tamil. \u2013 Podemos hacer una escalera de apoyo al aprendizaje del ingles. Ok. \u2013 Pondremos el alfabeto y palabras b\u00e1sicas. Ese fue el raudo comienzo del proyecto.<\/p>\n<p>Dos d\u00edas despu\u00e9s hab\u00edamos decidido los colores de la base y el acabado, blanco y azul Cerde\u00f1a. De modo que la primera semana la escalera comenz\u00f3 a ser enlucida e imprimada para acoger la pintura mural.<\/p>\n<p>A mi me gustaban sus huellas. Las huellas de todas las manos en el muro. De grasa, arena, arroz\u00a0\u00a0y manitas con <em>chutney<\/em>\u00a0y c<em>hicken Biryani.<\/em> Hablaban de su historia, y me hubiera gustado sacar monos, perros gatos y aparecidos de entre las sombras, como hice en la serie \u201cLos aparecidos\u201d. Pero aprovechar la mugre cuando busc\u00e1bamos proporcionarles un espacio limpio no parec\u00eda lo mas razonable. As\u00ed que me puse a pensar. \u2013 No elegiremos nosotras las palabras, porque no tenemos ni la edad, ni la cultura apropiada. Las elegir\u00e1n las personas que la usan, maestras, estudiantes, estudiantas y personal de la escuela. As\u00ed fue como dise\u00f1\u00e9 la encuesta: \u00bfCu\u00e1l es tu palabra favorita? Y una calurosa jornada de abril entre las 9 y las 5 de la tarde, Virginie, la Diosa de la Luna y yo, nos decidimos a pasarla a doscientas personitas tamil-hablantes, de entre 4 y 14 a\u00f1os.<\/p>\n<p><strong>LAS PALABRAS FAVORITAS<\/strong><\/p>\n<p>Las palabras favoritas son: \u00e1rbol, manzana, monta\u00f1a, naturaleza, flor, mango, estrella, sol, pavo real, tigre o mariposa. Y tambi\u00e9n: casa, coche, edificio, palacio, sem\u00e1foro, tel\u00e9fono m\u00f3vil y motocicleta. Me pregunto cu\u00e1l hubiera sido su palabra favorita si no hubieran tenido que dibujarla. Porque la m\u00eda, dif\u00edcilmente dibujable, es amor.<\/p>\n<p>La sesi\u00f3n fue energ\u00e9tica, calurosa, agotadora y vital. Pod\u00e9is leer lo que sent\u00ed en ese momento en el post titulado <em><a href=\"http:\/\/trementinalux.com\/Blog\/happyness-for-come-back-to-school\/\">Happyness for come back to school.<\/a><\/em><\/p>\n<p>Llegados a este punto, pas\u00e9 dos semanas catalogando palabras\u00a0y dibujos\u00a0sin saber muy bien qu\u00e9 hacer con ellos, m\u00e1s all\u00e1 de un art\u00edculo de investigaci\u00f3n que tengo en el tintero. En este tiempo le facilit\u00e9 a Virginie el <em>planning<\/em> del proyecto, con los tiempos, las intenciones y el presupuesto, a la espera de que la idea final se concretara. Y en efecto, una noche de insomnio, apurando el l\u00edmite del plazo previsto, el proyecto se desvel\u00f3. Este es su t\u00edtulo:<\/p>\n<p><strong>THE MAGIC ALPHABETICAL STAIRS.<\/strong>\u00a0 Click here to know the project:\u00a0<strong><a href=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/Magic-alphabetical-stairs-lr.pdf\">Magic alphabetical stairs<\/a><\/strong><\/p>\n<p><strong>Parte 2. Inoculando la semilla del amor al arte y la gesti\u00f3n cultural<\/strong><\/p>\n<p>La vida en Chennai esta llena de oportunidades inimaginables y gente maravillosa, pero exige renuncias f\u00edsicas muy importantes. En Chennai es muy dif\u00edcil andar de un sitio a otro, no hay aceras o no son seguras, tardas un par de a\u00f1os en lanzarte a caminar como una persona local. No es posible ir en bici si no has nacido aqu\u00ed. Tampoco puedes conducir, te conducen. Apenas hay parques p\u00fablicos, ni jardines. Apenas hay museos de arte, ni polideportivos, ni piscinas p\u00fablicas, ni sem\u00e1foros ni rotondas y la se baila maravillosamente en los entierros. Museos hay algunos, pero est\u00e1n a 43 grados con la obra ardiendo. Pero eso es otro tema, aqu\u00ed una foto del <a href=\"http:\/\/trementinalux.com\/Blog\/siete-consejos-de-una-mediterranea-para-vivir-en-india-una-temporadita-larga\/\">museo antropol\u00f3gico.<\/a><\/p>\n<p>Esa noche, la noche en que o encontraba una soluci\u00f3n o renunciaba al proyecto, so\u00f1\u00e9 con marcos de oro. Muchos marcos de oro. Y despert\u00e9 pensando en enmarcar en oro los trabajos de los ni\u00f1os y las ni\u00f1as,\u00a0contribuyendo a crear un museo de arte en su entorno escolar para poner en valor su trabajo mediante la apelaci\u00f3n simb\u00f3lica a la cultura del oro. El oro aqu\u00ed es tan abundante como las naranjas en Valencia o el Pulpo a Feira en Galicia. Lo cierto es que no conf\u00edan en los bancos, las rupias y las inclemencias del Monz\u00f3n y prefieren llevar encima todo lo que poseen, todo su oro y sus joyas, desde que nacen.<\/p>\n<p>Yo soy bastante anti museo de gesti\u00f3n vertical, porque todos acaban siendo excluyentes, basados en la dominaci\u00f3n y la competitividad, par\u00e1metros patriarcales obsoletos entre los que se desliza, en los m\u00e1s pioneros, alguna actividad participativa. Tampoco soy de andar aleccionando con lo bueno de \u00aboccidente\u00bb porque tenemos m\u00e1s que aprender que ense\u00f1ar, o mejor dicho, en la mezcla est\u00e1 la gracia. Sin embargo, he utilizado en este proyecto una puesta en valor del patrimonio a trav\u00e9s del c\u00f3digo decimon\u00f3nico del sal\u00f3n de arte porque educa en la posibilidad de que lo que hagas no acabe en una escombrera y de paso siembra la semilla del: \u201cma\u00f1ana yo har\u00e9 arte o gestionar\u00e9 mi propio espacio para el arte\u201d, porque el p\u00fablico potencial est\u00e1 entre cuatro y catorce\u00a0a\u00f1os.<\/p>\n<p>Y este es el proyecto que dise\u00f1\u00e9 y que <em>Namma Beach Namma Chennai<\/em> aprob\u00f3 y financi\u00f3.<\/p>\n<p><strong>PARTE 3. Coordinar y\u00a0crear. Las tres\u00a0\u00abC\u00bb: colectivo, colaborativo, contributivo.<\/strong><\/p>\n<p>Con los deberes hechos y la pintura comprada, la aventura de comprar pintura aqu\u00ed requiere un post entero y varias horas en el mostrador, nos presentamos en el colegio una calurosa ma\u00f1ana de mayo, dispuestas a empezar a plantear la composici\u00f3n global. El proyecto se desarrolla sobre muros complejos, con mirada m\u00faltiple y facetada, de ascenso y de descenso. No es un plano sencillo, as\u00ed que tuve que crear una maqueta en carton\u00e9 para manejarme con los vol\u00famenes, la jerarqu\u00eda, la narraci\u00f3n y el recorrido visual.<\/p>\n<p>En la planta baja la figura de una mujer inspirada en Miss Daisy, profesora del cole, sopla el alfabeto, es la primera altura de la escalera con la que conviven las personitas m\u00e1s peque\u00f1as y por eso tiene la informaci\u00f3n m\u00e1s b\u00e1sica e importante. En la escalera, con la barandilla y los marcos de oro con tintas planas se sit\u00faan las palabras y los dibujos que obtuvimos en la encuesta. En el descansillo pint\u00e9 el retrato de un peque\u00f1o h\u00e9roe con un tigre, porque el tigre es una especie de querido animal nacional,adem\u00e1s del pavo real, que presenta coraje y fortaleza para llevar adelante los proyectos. Esta especie de falso <em>selfie<\/em> del momento microhist\u00f3rico, permite una identificaci\u00f3n global, un no olvidar qui\u00e9n y porqu\u00e9 son los y las protagonistas de la escuela. En la parte superior, por la que se accede a los cursos m\u00e1s altos vive el \u00e1rbol de la literatura, un \u00e1rbol hecho con trazos de palabras y lindas frases hiladas que se hermana con el \u00e1rbol vivo que late a su lado, maravilloso guardi\u00e1n del patio.<\/p>\n<p>El primer d\u00eda planteamos la estructura del dibujo entre dos personas. El segundo, arrancamos a pintar un equipo de cuatro personas. En los d\u00edas sucesivos el equipo se incremento a diecis\u00e9is personas pintando y cinco de apoyo con los andamios, de todas las edades, sexos y etnias e independientemente de su formaci\u00f3n pict\u00f3rica, con enf\u00e1ticas ganas de participar, e incluso asistiendo a horas desiguales, en las que yo no pod\u00eda supervisar el proyecto, tan solo facilitar instrucciones y consejos por whassap.<\/p>\n<p>Coordinar los procesos y asegurar una paleta y un modo de hacer com\u00fan ha sido sin duda el mayor reto del proyecto. Miento, el mayor reto ha sido pintar a 45 grados y con mosquitos, al atardecer.<\/p>\n<p>Me siento orgullosa de presentaros un proyecto de gesti\u00f3n cultural e intervenci\u00f3n pict\u00f3rica educativa en el que han participado m\u00e1s de 250 personas, en el que cada una de ellas ha hecho suya la idea, las palabras y las pinceladas, en un complejo entramado de ilusi\u00f3n, solidaridad, afecto y apoyo mutuo.<\/p>\n<p>Gracias a <em>Namma Beach Namma Chennai<\/em>, el personal y las personitas que estudian en el Injambakkam School, especialmente a Regina por su maravilloso T\u00e9 Chai. Gracias muy especiales a Virginie y Alexandrina por su incre\u00edble dedicaci\u00f3n, constancia, armon\u00eda, cari\u00f1o y capacidad resolutiva, a Yasmine, Catherine, Andrea, Claire, Dauphine, J\u00falia, Roberto, Amandine, Ines, Alex, Balappam y Michael por creer en esto.<\/p>\n<p>TREMENTINA ALWAYS THANKS AND LUX<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-5290\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS18-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5289\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS17-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5288\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS16-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5287\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS15-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5281\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9.jpg\" alt=\"\" width=\"640\" height=\"960\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9.jpg 640w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9-200x300.jpg 200w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9-580x870.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9-380x570.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS9-280x420.jpg 280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-5296\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5297\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS28-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-5282\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10.jpg\" alt=\"\" width=\"640\" height=\"960\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10.jpg 640w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10-200x300.jpg 200w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10-580x870.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10-380x570.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS10-280x420.jpg 280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-5291\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS4-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5295\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS26-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5294\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS25-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5293\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS23-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5292\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS21-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-5283\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11.jpg\" alt=\"\" width=\"640\" height=\"960\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11.jpg 640w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11-200x300.jpg 200w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11-580x870.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11-380x570.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS11-280x420.jpg 280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-5305\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS39-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5304\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5303\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46.jpg\" alt=\"\" width=\"640\" height=\"852\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46.jpg 640w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-225x300.jpg 225w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-580x772.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-380x506.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-280x373.jpg 280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5302\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><img decoding=\"async\" class=\"alignnone size-full wp-image-5284\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS12-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5285\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS13-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5280\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS8-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5278\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS6-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5279\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS7-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5277\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS3-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5276\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS2jpg-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5275\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS1-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-5300\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS36-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-highium wp-image-5301\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS41-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-highium wp-image-5302\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS45-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-highium wp-image-5303\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46.jpg\" alt=\"\" width=\"640\" height=\"852\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46.jpg 640w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-225x300.jpg 225w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-580x772.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-380x506.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS46-280x373.jpg 280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5304\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-300x169.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-768x432.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-580x326.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-380x214.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS47-280x158.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-5299\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34.jpg 960w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34-300x200.jpg 300w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34-768x512.jpg 768w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34-580x387.jpg 580w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34-380x253.jpg 380w, https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS34-280x187.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Let me tell you a lovely story, once upon a time, recently&#8230; Parte 1. Tienes que conocer a Virginie. A ella le hab\u00edan hablado de m\u00ed. Y a m\u00ed, de ella. Un d\u00eda, en el\u00a0Lunch mexicano que organiz\u00f3 una maravillosa amiga en com\u00fan, gracias Vero, nos conocimos. A los dos minutos\u00a0Virginie me propuso pintar una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,301,113],"tags":[337,326,338,288,336,340,339],"class_list":["post-4734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-otras-delicias-vindicativas","category-gender-studies","category-obra","tag-artproject","tag-chennai","tag-educational","tag-india","tag-kids","tag-namma-beach-namma-chennai","tag-painting"],"jetpack_featured_media_url":"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2018\/05\/MAGIC-STAIRS27.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/comments?post=4734"}],"version-history":[{"count":11,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4734\/revisions"}],"predecessor-version":[{"id":5311,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/4734\/revisions\/5311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media\/5296"}],"wp:attachment":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media?parent=4734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/categories?post=4734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags?post=4734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}