{"id":3857,"date":"2014-09-18T10:55:16","date_gmt":"2014-09-18T10:55:16","guid":{"rendered":"http:\/\/trementinalux.com\/Blog\/?p=3857"},"modified":"2016-03-29T07:06:47","modified_gmt":"2016-03-29T07:06:47","slug":"la-resistencia","status":"publish","type":"post","link":"https:\/\/trementinalux.com\/Blog\/la-resistencia\/","title":{"rendered":"\u00abLa Resistencia\u00bb. Secuencia del Amor Universal, 21 de 219 \u00f3 276"},"content":{"rendered":"<p>La verdad es que no recuerdo ni d\u00f3nde ni cu\u00e1ndo te pinto. S\u00e9 que lo hago con horizontales y verticales crom\u00e1ticas. Casi sin buscar detalle, explorando el color, investigando la l\u00ednea recta con los l\u00e1pices acuarelables sobre la agenda. Estudio la superposici\u00f3n. Pinto cuando pinto y luego escribo y publico y difundo y transporto mi arte a pie por las calles de la ciudad y hago mudanzas de \u00abSalitas de ser\u00bb en bici. Las marchantes me dicen que estoy loca por hacerlo todo sola, que qu\u00e9 hago aqu\u00ed. Los <em>conneiseurs<\/em> ven \u00abLa evoluci\u00f3n del Yo\u00bb y se admiran de la fuerza del trazo, me preguntan si el pintor es italiano y cuando les digo que soy yo, mujer, pizpireta y bajita, sonr\u00eden incr\u00e9dulos y se van. En fin, resistencia, ante el silencio, la indiferencia, la duda, la soledad, el \u00e9xito y el fracaso, la inconsistencia y el iceberg, lo que podemos, queremos, sabemos hacer, el amor y el desamor. <\/p>\n<p>Gracias a quienes est\u00e1is. La marchante se equivoca. No estoy sola. La Resistencia est\u00e1 aqu\u00ed.<\/p>\n<p>TREMENTINA LUX \u00a9 2014<br \/>\n#SecuenciadelAmorUniversal<br \/>\n#LaResistencia<br \/>\n#BringBackOurGirls<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La verdad es que no recuerdo ni d\u00f3nde ni cu\u00e1ndo te pinto. S\u00e9 que lo hago con horizontales y verticales crom\u00e1ticas. Casi sin buscar detalle, explorando el color, investigando la l\u00ednea recta con los l\u00e1pices acuarelables sobre la agenda. Estudio la superposici\u00f3n. Pinto cuando pinto y luego escribo y publico y difundo y transporto mi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,113,300],"tags":[257,252,248],"class_list":["post-3857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-otras-delicias-vindicativas","category-obra","category-secuenciadelamoruniversal","tag-bringbackourgirls-2","tag-ninas-nigerianas","tag-secuencia-del-amor-universal"],"jetpack_featured_media_url":"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2014\/07\/LARESISTENCIA.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/comments?post=3857"}],"version-history":[{"count":6,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3857\/revisions"}],"predecessor-version":[{"id":3863,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3857\/revisions\/3863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media\/3801"}],"wp:attachment":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media?parent=3857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/categories?post=3857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags?post=3857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}