{"id":3730,"date":"2014-08-29T21:20:53","date_gmt":"2014-08-29T21:20:53","guid":{"rendered":"http:\/\/trementinalux.com\/Blog\/?p=3730"},"modified":"2016-03-29T06:59:40","modified_gmt":"2016-03-29T06:59:40","slug":"pequena-ira-sin-nombre-secuencia-del-amor-universal19-de-219-o-276","status":"publish","type":"post","link":"https:\/\/trementinalux.com\/Blog\/pequena-ira-sin-nombre-secuencia-del-amor-universal19-de-219-o-276\/","title":{"rendered":"\u00abPeque\u00f1a Ira\u00bb Secuencia del Amor Universal,19 de 219 \u00f3 276"},"content":{"rendered":"<p>No preguntes qu\u00e9 pasa con tu ojo.<br \/>\nEs el ojo derecho, el ojo del padre.<\/p>\n<p>Estoy sentada contigo encima<br \/>\nviene a ducharse<br \/>\nestamos en una piscina<br \/>\nt\u00fa y yo Peque\u00f1a Ira, lo sabemos<br \/>\nque el goce y lo precario<br \/>\nson esenciales.<\/p>\n<p>Esto es ahora el paisaje.<br \/>\nEl paisaje es una piscina<br \/>\ny ese hombre viene a ducharse.<\/p>\n<p>Agita su barriga<br \/>\npellizca su glande<br \/>\nhincha sus carrillos<br \/>\nescupe<br \/>\nsalpica<br \/>\ncomo un mal bukake.<\/p>\n<p>Es agosto<br \/>\ny \u00e9l se ha ido<br \/>\nindicio en tu ojo<br \/>\nsin embargo,<br \/>\ndel padre<br \/>\nla ira<br \/>\ny el cloro.<\/p>\n<p>TREMENTINA LUX \u00a9 2014<br \/>\n#BringBackOurGirls<br \/>\n#SecuenciadelAmorUniversal<br \/>\n#Peque\u00f1aIra<\/p>\n<p>Y Ma\u00f1ana o pasado 20&#8230;<br \/>\n<div id=\"attachment_3744\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2014\/08\/FELICIDADDETALLE2-e1409346766117.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3744\" src=\"http:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2014\/08\/FELICIDADDETALLE2-300x168.jpg\" alt=\"FELICIDAD DETALLE\" width=\"300\" height=\"168\" class=\"size-medium wp-image-3744\" \/><\/a><p id=\"caption-attachment-3744\" class=\"wp-caption-text\">FELICIDAD DETALLE<\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No preguntes qu\u00e9 pasa con tu ojo. Es el ojo derecho, el ojo del padre. Estoy sentada contigo encima viene a ducharse estamos en una piscina t\u00fa y yo Peque\u00f1a Ira, lo sabemos que el goce y lo precario son esenciales. Esto es ahora el paisaje. El paisaje es una piscina y ese hombre viene [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,113,300],"tags":[257,252,248],"class_list":["post-3730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-otras-delicias-vindicativas","category-obra","category-secuenciadelamoruniversal","tag-bringbackourgirls-2","tag-ninas-nigerianas","tag-secuencia-del-amor-universal"],"jetpack_featured_media_url":"https:\/\/trementinalux.com\/Blog\/wp-content\/uploads\/2014\/08\/PEQUE\u00d1AIRASINNOMBRE.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/comments?post=3730"}],"version-history":[{"count":16,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3730\/revisions"}],"predecessor-version":[{"id":3749,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/posts\/3730\/revisions\/3749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media\/3733"}],"wp:attachment":[{"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/media?parent=3730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/categories?post=3730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trementinalux.com\/Blog\/wp-json\/wp\/v2\/tags?post=3730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}